{"id":7156,"date":"2023-04-12T15:23:55","date_gmt":"2023-04-12T15:23:55","guid":{"rendered":"https:\/\/www.tilda.com\/fr-ca\/?post_type=recipes&#038;p=7156"},"modified":"2024-05-02T13:20:20","modified_gmt":"2024-05-02T13:20:20","slug":"biryani-vegetalien","status":"publish","type":"recipes","link":"https:\/\/www.tilda.com\/fr-ca\/recettes\/biryani-vegetalien\/","title":{"rendered":"Biryani v\u00e9g\u00e9talien"},"content":{"rendered":"<section class=\"content-section u-hide-print content-section--pink\">\n    <div class=\"container container--no-pad-mobile\">\n        <div class=\"container container--small\">\n            <h2 class=\"u-text-center title title__rice title__rice--left-2 title__rice--right-3\"><span>Plus<\/span> <span>de<\/span> <span class=\"title--outline\">recettes<\/span><\/h2>\n                    <\/div>\n        \n        <div class=\"u-text-center u-padded slider slider--stretched slider--nav-bottom-wide slider--nav-navy slider--offset-mobile\">\n\n            <div data-behaviour=\"related-slider\">\n\n                                                            <div data-behaviour=\"after-slider\">\n                            \n<a class=\"box\" href=\"https:\/\/www.tilda.com\/fr-ca\/recettes\/biryani-dagneau-dhyderabad\/\" aria-labelledby=\"card-subtitle-7550 card-title-7550 card-excerpt-7550\">\n    <div class=\"box__image\">\n\t\t                    \t<img decoding=\"async\" loading=\"lazy\" width=\"450\" height=\"400\" src=\"https:\/\/www.tilda.com\/fr-ca\/wp-content\/uploads\/sites\/6\/2024\/09\/Lamb-Biryani-herbed.png\"  alt=\"\"\/>\n\t\t\t\t        <div class=\"box__overlay \"><span class=\"box__view\">\n                            Afficher la recette\n                    <\/span><\/div>\n    <\/div>\n    <div class=\"box__content\">\n                    <p class=\"box__subtitle h6\" id=\"card-subtitle-7550\">Grand Riz Basmati A Grain Extra Long<\/p>\n                <p class=\"box__title h5\" id=\"card-title-7550\">Biryani d\u2019agneau d\u2019Hyderabad<\/p>\n                            <\/div>\n<\/a>                        <\/div>\n                                                                <\/div>\n                            <a href=\"\/fr-ca\/recettes\/\" class=\"button\">Plus de recettes<\/a>\n                    <\/div>\n    <\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>Il n\u2019y a rien de mieux qu\u2019une assiette de \u00ab biryani \u00bb typique, compos\u00e9 de succulents morceaux de viande ou de l\u00e9gumes. Ce biryani v\u00e9g\u00e9talien \u00e0 base de pois chiches ne contient pas de produits laitiers, de ghee ou de lait. Ces produits ont \u00e9t\u00e9 judicieusement remplac\u00e9s par des ingr\u00e9dients d\u2019origine v\u00e9g\u00e9tale. Le m\u00e9lange d\u2019herbes fra\u00eeches et d\u2019\u00e9pices savoureuses donne vie au plat sans compromettre les saveurs magiques d\u2019un biryani traditionnel.<\/p>\n","protected":false},"featured_media":7157,"menu_order":0,"template":"","meta":{"_acf_changed":false,"editor_notices":[],"footnotes":""},"range":[],"ingredients":[306],"meal":[302],"cuisine":[312],"dish":[],"time":[183],"difficulty":[311],"recipes-dietary":[],"industry":[],"class_list":["post-7156","recipes","type-recipes","status-publish","has-post-thumbnail","hentry","ingredients-legumes","meal-diner","cuisine-indien","time-0-30-minutes","difficulty-facile"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Biryani v\u00e9g\u00e9talien | Tilda<\/title>\n<meta name=\"description\" content=\"Il n\u2019y a rien de mieux qu\u2019une assiette de \u00ab biryani \u00bb typique, compos\u00e9 de succulents morceaux de viande ou de l\u00e9gumes. Ce biryani v\u00e9g\u00e9talien \u00e0 base de pois chiches ne contient pas de produits laitiers, de ghee ou de lait. Ces produits ont \u00e9t\u00e9 judicieusement remplac\u00e9s par des ingr\u00e9dients d\u2019origine v\u00e9g\u00e9tale. Le m\u00e9lange d\u2019herbes fra\u00eeches et d\u2019\u00e9pices savoureuses donne vie au plat sans compromettre les saveurs magiques d\u2019un biryani traditionnel.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tilda.com\/fr-ca\/recettes\/biryani-vegetalien\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Biryani v\u00e9g\u00e9talien\" \/>\n<meta property=\"og:description\" content=\"Il n\u2019y a rien de mieux qu\u2019une assiette de \u00ab biryani \u00bb typique, compos\u00e9 de succulents morceaux de viande ou de l\u00e9gumes. Ce biryani v\u00e9g\u00e9talien \u00e0 base de pois chiches ne contient pas de produits laitiers, de ghee ou de lait. Ces produits ont \u00e9t\u00e9 judicieusement remplac\u00e9s par des ingr\u00e9dients d\u2019origine v\u00e9g\u00e9tale. Le m\u00e9lange d\u2019herbes fra\u00eeches et d\u2019\u00e9pices savoureuses donne vie au plat sans compromettre les saveurs magiques d\u2019un biryani traditionnel.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tilda.com\/fr-ca\/recettes\/biryani-vegetalien\/\" \/>\n<meta property=\"og:site_name\" content=\"Tilda Rice Canada Fran\u00e7ais\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-02T13:20:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tilda.com\/fr-ca\/wp-content\/uploads\/sites\/6\/2023\/04\/12151305\/Biryani-small.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tilda.com\\\/fr-ca\\\/recettes\\\/biryani-vegetalien\\\/\",\"url\":\"https:\\\/\\\/www.tilda.com\\\/fr-ca\\\/recettes\\\/biryani-vegetalien\\\/\",\"name\":\"Biryani v\u00e9g\u00e9talien | Tilda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tilda.com\\\/fr-ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tilda.com\\\/fr-ca\\\/recettes\\\/biryani-vegetalien\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tilda.com\\\/fr-ca\\\/recettes\\\/biryani-vegetalien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tilda.com\\\/fr-ca\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/04\\\/12151305\\\/Biryani-small.jpg\",\"datePublished\":\"2023-04-12T15:23:55+00:00\",\"dateModified\":\"2024-05-02T13:20:20+00:00\",\"description\":\"Il n\u2019y a rien de mieux qu\u2019une assiette de \u00ab biryani \u00bb typique, compos\u00e9 de succulents morceaux de viande ou de l\u00e9gumes. Ce biryani v\u00e9g\u00e9talien \u00e0 base de pois chiches ne contient pas de produits laitiers, de ghee ou de lait. Ces produits ont \u00e9t\u00e9 judicieusement remplac\u00e9s par des ingr\u00e9dients d\u2019origine v\u00e9g\u00e9tale. Le m\u00e9lange d\u2019herbes fra\u00eeches et d\u2019\u00e9pices savoureuses donne vie au plat sans compromettre les saveurs magiques d\u2019un biryani traditionnel.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tilda.com\\\/fr-ca\\\/recettes\\\/biryani-vegetalien\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tilda.com\\\/fr-ca\\\/recettes\\\/biryani-vegetalien\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/www.tilda.com\\\/fr-ca\\\/recettes\\\/biryani-vegetalien\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tilda.com\\\/fr-ca\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/04\\\/12151305\\\/Biryani-small.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tilda.com\\\/fr-ca\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/04\\\/12151305\\\/Biryani-small.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tilda.com\\\/fr-ca\\\/recettes\\\/biryani-vegetalien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.tilda.com\\\/fr-ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Recettes\",\"item\":\"https:\\\/\\\/www.tilda.com\\\/fr-ca\\\/recettes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Biryani v\u00e9g\u00e9talien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tilda.com\\\/fr-ca\\\/#website\",\"url\":\"https:\\\/\\\/www.tilda.com\\\/fr-ca\\\/\",\"name\":\"Tilda Rice Canada Fran\u00e7ais\",\"description\":\"All things Basmati\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tilda.com\\\/fr-ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Biryani v\u00e9g\u00e9talien | Tilda","description":"Il n\u2019y a rien de mieux qu\u2019une assiette de \u00ab biryani \u00bb typique, compos\u00e9 de succulents morceaux de viande ou de l\u00e9gumes. Ce biryani v\u00e9g\u00e9talien \u00e0 base de pois chiches ne contient pas de produits laitiers, de ghee ou de lait. Ces produits ont \u00e9t\u00e9 judicieusement remplac\u00e9s par des ingr\u00e9dients d\u2019origine v\u00e9g\u00e9tale. Le m\u00e9lange d\u2019herbes fra\u00eeches et d\u2019\u00e9pices savoureuses donne vie au plat sans compromettre les saveurs magiques d\u2019un biryani traditionnel.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tilda.com\/fr-ca\/recettes\/biryani-vegetalien\/","og_locale":"fr_CA","og_type":"article","og_title":"Biryani v\u00e9g\u00e9talien","og_description":"Il n\u2019y a rien de mieux qu\u2019une assiette de \u00ab biryani \u00bb typique, compos\u00e9 de succulents morceaux de viande ou de l\u00e9gumes. Ce biryani v\u00e9g\u00e9talien \u00e0 base de pois chiches ne contient pas de produits laitiers, de ghee ou de lait. Ces produits ont \u00e9t\u00e9 judicieusement remplac\u00e9s par des ingr\u00e9dients d\u2019origine v\u00e9g\u00e9tale. Le m\u00e9lange d\u2019herbes fra\u00eeches et d\u2019\u00e9pices savoureuses donne vie au plat sans compromettre les saveurs magiques d\u2019un biryani traditionnel.","og_url":"https:\/\/www.tilda.com\/fr-ca\/recettes\/biryani-vegetalien\/","og_site_name":"Tilda Rice Canada Fran\u00e7ais","article_modified_time":"2024-05-02T13:20:20+00:00","og_image":[{"url":"https:\/\/www.tilda.com\/fr-ca\/wp-content\/uploads\/sites\/6\/2023\/04\/12151305\/Biryani-small.jpg","width":1,"height":1,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tilda.com\/fr-ca\/recettes\/biryani-vegetalien\/","url":"https:\/\/www.tilda.com\/fr-ca\/recettes\/biryani-vegetalien\/","name":"Biryani v\u00e9g\u00e9talien | Tilda","isPartOf":{"@id":"https:\/\/www.tilda.com\/fr-ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tilda.com\/fr-ca\/recettes\/biryani-vegetalien\/#primaryimage"},"image":{"@id":"https:\/\/www.tilda.com\/fr-ca\/recettes\/biryani-vegetalien\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tilda.com\/fr-ca\/wp-content\/uploads\/sites\/6\/2023\/04\/12151305\/Biryani-small.jpg","datePublished":"2023-04-12T15:23:55+00:00","dateModified":"2024-05-02T13:20:20+00:00","description":"Il n\u2019y a rien de mieux qu\u2019une assiette de \u00ab biryani \u00bb typique, compos\u00e9 de succulents morceaux de viande ou de l\u00e9gumes. Ce biryani v\u00e9g\u00e9talien \u00e0 base de pois chiches ne contient pas de produits laitiers, de ghee ou de lait. Ces produits ont \u00e9t\u00e9 judicieusement remplac\u00e9s par des ingr\u00e9dients d\u2019origine v\u00e9g\u00e9tale. Le m\u00e9lange d\u2019herbes fra\u00eeches et d\u2019\u00e9pices savoureuses donne vie au plat sans compromettre les saveurs magiques d\u2019un biryani traditionnel.","breadcrumb":{"@id":"https:\/\/www.tilda.com\/fr-ca\/recettes\/biryani-vegetalien\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tilda.com\/fr-ca\/recettes\/biryani-vegetalien\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.tilda.com\/fr-ca\/recettes\/biryani-vegetalien\/#primaryimage","url":"https:\/\/www.tilda.com\/fr-ca\/wp-content\/uploads\/sites\/6\/2023\/04\/12151305\/Biryani-small.jpg","contentUrl":"https:\/\/www.tilda.com\/fr-ca\/wp-content\/uploads\/sites\/6\/2023\/04\/12151305\/Biryani-small.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tilda.com\/fr-ca\/recettes\/biryani-vegetalien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.tilda.com\/fr-ca\/"},{"@type":"ListItem","position":2,"name":"Recettes","item":"https:\/\/www.tilda.com\/fr-ca\/recettes\/"},{"@type":"ListItem","position":3,"name":"Biryani v\u00e9g\u00e9talien"}]},{"@type":"WebSite","@id":"https:\/\/www.tilda.com\/fr-ca\/#website","url":"https:\/\/www.tilda.com\/fr-ca\/","name":"Tilda Rice Canada Fran\u00e7ais","description":"All things Basmati","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tilda.com\/fr-ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"}]}},"_links":{"self":[{"href":"https:\/\/www.tilda.com\/fr-ca\/wp-json\/wp\/v2\/recipes\/7156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tilda.com\/fr-ca\/wp-json\/wp\/v2\/recipes"}],"about":[{"href":"https:\/\/www.tilda.com\/fr-ca\/wp-json\/wp\/v2\/types\/recipes"}],"version-history":[{"count":0,"href":"https:\/\/www.tilda.com\/fr-ca\/wp-json\/wp\/v2\/recipes\/7156\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tilda.com\/fr-ca\/wp-json\/wp\/v2\/media\/7157"}],"wp:attachment":[{"href":"https:\/\/www.tilda.com\/fr-ca\/wp-json\/wp\/v2\/media?parent=7156"}],"wp:term":[{"taxonomy":"range","embeddable":true,"href":"https:\/\/www.tilda.com\/fr-ca\/wp-json\/wp\/v2\/range?post=7156"},{"taxonomy":"ingredients","embeddable":true,"href":"https:\/\/www.tilda.com\/fr-ca\/wp-json\/wp\/v2\/ingredients?post=7156"},{"taxonomy":"meal","embeddable":true,"href":"https:\/\/www.tilda.com\/fr-ca\/wp-json\/wp\/v2\/meal?post=7156"},{"taxonomy":"cuisine","embeddable":true,"href":"https:\/\/www.tilda.com\/fr-ca\/wp-json\/wp\/v2\/cuisine?post=7156"},{"taxonomy":"dish","embeddable":true,"href":"https:\/\/www.tilda.com\/fr-ca\/wp-json\/wp\/v2\/dish?post=7156"},{"taxonomy":"time","embeddable":true,"href":"https:\/\/www.tilda.com\/fr-ca\/wp-json\/wp\/v2\/time?post=7156"},{"taxonomy":"difficulty","embeddable":true,"href":"https:\/\/www.tilda.com\/fr-ca\/wp-json\/wp\/v2\/difficulty?post=7156"},{"taxonomy":"recipes-dietary","embeddable":true,"href":"https:\/\/www.tilda.com\/fr-ca\/wp-json\/wp\/v2\/recipes-dietary?post=7156"},{"taxonomy":"industry","embeddable":true,"href":"https:\/\/www.tilda.com\/fr-ca\/wp-json\/wp\/v2\/industry?post=7156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}